{"id":7046,"date":"2024-04-05T10:05:15","date_gmt":"2024-04-05T10:05:15","guid":{"rendered":"https:\/\/benin.ironmansupplementsafrica.com\/?post_type=product&#038;p=7046"},"modified":"2024-04-05T10:05:15","modified_gmt":"2024-04-05T10:05:15","slug":"applied-critical-whey-5lbs","status":"publish","type":"product","link":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/","title":{"rendered":"APPLIED CRITICAL WHEY 5lbs"},"content":{"rendered":"<p>CONSTRUIRE ET MAINTENIR MUSCLE : La poudre de prot\u00e9ine Applied Nutrition est un excellent moyen de d\u00e9velopper vos muscles lorsque vous faites de l&rsquo;entra\u00eenement en force. Les prot\u00e9ines sont un \u00e9l\u00e9ment essentiel de votre alimentation pour aider \u00e0 maintenir votre masse musculaire, donc boire le shake comme recommand\u00e9 vous aidera \u00e0 maintenir votre d\u00e9veloppement musculaire.<br \/>\nFACILE \u00c0 PR\u00c9PARER : Cette poudre riche en prot\u00e9ines se m\u00e9lange incroyablement bien avec de l\u2019eau ou du lait faible en gras. Vous pouvez le secouer lorsque vous \u00eates en retard ou en d\u00e9placement en un rien de temps.<br \/>\nTest\u00e9 pour les athl\u00e8tes : chaque ingr\u00e9dient de ce produit est soigneusement s\u00e9lectionn\u00e9 et contr\u00f4l\u00e9 via notre syst\u00e8me de gestion de la qualit\u00e9 pour vous apporter le plus haut niveau d&rsquo;assurance. Les produits finaux sont fabriqu\u00e9s et emball\u00e9s dans un laboratoire accr\u00e9dit\u00e9 ISO 22000, BRC, GMP et Halal.<br \/>\nVARI\u00c9T\u00c9 DE SAVEURS FANTASTIQUES\u00a0: Vous pouvez choisir parmi plusieurs saveurs disponibles pour votre milkshake prot\u00e9in\u00e9. Vous n\u2019aurez plus jamais besoin de boire des suppl\u00e9ments prot\u00e9in\u00e9s insipides.<br \/>\nGRANDE SOURCE DE PROT\u00c9INES : La poudre de lactos\u00e9rum Critical Whey d&rsquo;Applied Nutrition est une merveilleuse source de prot\u00e9ines. La combinaison de concentr\u00e9 de prot\u00e9ines de lactos\u00e9rum, d&rsquo;isolat de prot\u00e9ines de lactos\u00e9rum et de prot\u00e9ines de lactos\u00e9rum hydrolys\u00e9es constitue le compl\u00e9ment id\u00e9al pour le d\u00e9veloppement musculaire.<img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-7047 size-large\" src=\"http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2024\/04\/CRITICAL-WHEY-1024x1024.png\" alt=\"\" width=\"980\" height=\"980\" srcset=\"http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2024\/04\/CRITICAL-WHEY-1024x1024.png 1024w, http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2024\/04\/CRITICAL-WHEY-300x300.png 300w, http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2024\/04\/CRITICAL-WHEY-150x150.png 150w, http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2024\/04\/CRITICAL-WHEY-768x768.png 768w, http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2024\/04\/CRITICAL-WHEY-324x324.png 324w, http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2024\/04\/CRITICAL-WHEY-416x416.png 416w, http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2024\/04\/CRITICAL-WHEY-100x100.png 100w, http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2024\/04\/CRITICAL-WHEY.png 1080w\" sizes=\"(max-width: 980px) 100vw, 980px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CONSTRUIRE ET MAINTENIR MUSCLE : La poudre de prot\u00e9ine Applied Nutrition est un excellent moyen de d\u00e9velopper vos muscles lorsque vous faites de l&rsquo;entra\u00eenement en force. Les prot\u00e9ines sont un \u00e9l\u00e9ment essentiel de votre alimentation pour aider \u00e0 maintenir votre masse musculaire, donc boire le shake comme recommand\u00e9 vous aidera \u00e0 maintenir votre d\u00e9veloppement musculaire. [&hellip;]<\/p>\n","protected":false},"featured_media":7047,"comment_status":"open","ping_status":"closed","template":"","meta":{"wds_primary_product_brand":0,"wds_primary_product_cat":0},"product_brand":[],"product_cat":[50],"product_tag":[],"class_list":["post-7046","product","type-product","status-publish","has-post-thumbnail","product_cat-protein-fr","first","instock","shipping-taxable","purchasable","product-type-simple"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"CONSTRUIRE ET MAINTENIR MUSCLE : La poudre de prot\u00e9ine Applied Nutrition est un excellent moyen de d\u00e9velopper vos muscles lorsque vous faites de l&#039;entra\u00eenement en force. Les prot\u00e9ines sont un \u00e9l\u00e9ment essentiel de votre alimentation pour aider \u00e0 maintenir votre masse musculaire, donc boire le shake comme recommand\u00e9 vous aidera \u00e0 maintenir votre d\u00e9veloppement musculaire.\" \/>\n\t<meta name=\"robots\" content=\"noindex, nofollow, max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"fr_FR\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Ironmansupplements Benin -\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"APPLIED CRITICAL WHEY 5lbs - Ironmansupplements Benin\" \/>\n\t\t<meta property=\"og:description\" content=\"CONSTRUIRE ET MAINTENIR MUSCLE : La poudre de prot\u00e9ine Applied Nutrition est un excellent moyen de d\u00e9velopper vos muscles lorsque vous faites de l&#039;entra\u00eenement en force. Les prot\u00e9ines sont un \u00e9l\u00e9ment essentiel de votre alimentation pour aider \u00e0 maintenir votre masse musculaire, donc boire le shake comme recommand\u00e9 vous aidera \u00e0 maintenir votre d\u00e9veloppement musculaire.\" \/>\n\t\t<meta property=\"og:url\" content=\"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/\" \/>\n\t\t<meta property=\"og:image\" content=\"http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2022\/11\/logo.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2024-04-05T10:05:15+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2024-04-05T10:05:15+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"APPLIED CRITICAL WHEY 5lbs - Ironmansupplements Benin\" \/>\n\t\t<meta name=\"twitter:description\" content=\"CONSTRUIRE ET MAINTENIR MUSCLE : La poudre de prot\u00e9ine Applied Nutrition est un excellent moyen de d\u00e9velopper vos muscles lorsque vous faites de l&#039;entra\u00eenement en force. Les prot\u00e9ines sont un \u00e9l\u00e9ment essentiel de votre alimentation pour aider \u00e0 maintenir votre masse musculaire, donc boire le shake comme recommand\u00e9 vous aidera \u00e0 maintenir votre d\u00e9veloppement musculaire.\" \/>\n\t\t<meta name=\"twitter:image\" content=\"http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2022\/11\/logo.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/produit\\\/applied-critical-whey-5lbs\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en#listItem\",\"position\":1,\"name\":\"Domicile\",\"item\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/boutique\\\/#listItem\",\"name\":\"Boutique\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/boutique\\\/#listItem\",\"position\":2,\"name\":\"Boutique\",\"item\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/boutique\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/categorie-produit\\\/protein-fr\\\/#listItem\",\"name\":\"Protein\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en#listItem\",\"name\":\"Domicile\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/categorie-produit\\\/protein-fr\\\/#listItem\",\"position\":3,\"name\":\"Protein\",\"item\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/categorie-produit\\\/protein-fr\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/produit\\\/applied-critical-whey-5lbs\\\/#listItem\",\"name\":\"APPLIED CRITICAL WHEY 5lbs\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/boutique\\\/#listItem\",\"name\":\"Boutique\"}},{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/produit\\\/applied-critical-whey-5lbs\\\/#listItem\",\"position\":4,\"name\":\"APPLIED CRITICAL WHEY 5lbs\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/categorie-produit\\\/protein-fr\\\/#listItem\",\"name\":\"Protein\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/produit\\\/applied-critical-whey-5lbs\\\/#itempage\",\"url\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/produit\\\/applied-critical-whey-5lbs\\\/\",\"name\":\"APPLIED CRITICAL WHEY 5lbs - Ironmansupplements Benin\",\"description\":\"CONSTRUIRE ET MAINTENIR MUSCLE : La poudre de prot\\u00e9ine Applied Nutrition est un excellent moyen de d\\u00e9velopper vos muscles lorsque vous faites de l'entra\\u00eenement en force. Les prot\\u00e9ines sont un \\u00e9l\\u00e9ment essentiel de votre alimentation pour aider \\u00e0 maintenir votre masse musculaire, donc boire le shake comme recommand\\u00e9 vous aidera \\u00e0 maintenir votre d\\u00e9veloppement musculaire.\",\"inLanguage\":\"fr-FR\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/produit\\\/applied-critical-whey-5lbs\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2024\\\/04\\\/CRITICAL-WHEY.png\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/produit\\\/applied-critical-whey-5lbs\\\/#mainImage\",\"width\":1080,\"height\":1080},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/produit\\\/applied-critical-whey-5lbs\\\/#mainImage\"},\"datePublished\":\"2024-04-05T10:05:15+00:00\",\"dateModified\":\"2024-04-05T10:05:15+00:00\"},{\"@type\":\"Organization\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/#organization\",\"name\":\"Ironmansupplements Benin\",\"url\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/wp-content\\\/uploads\\\/sites\\\/9\\\/2024\\\/02\\\/ironman_logo_112px_-removebg-preview.png\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/produit\\\/applied-critical-whey-5lbs\\\/#organizationLogo\",\"width\":112,\"height\":112},\"image\":{\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/produit\\\/applied-critical-whey-5lbs\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/\",\"name\":\"Ironmansupplements Benin\",\"inLanguage\":\"fr-FR\",\"publisher\":{\"@id\":\"http:\\\/\\\/benin.ironmansupplementsafrica.com\\\/en\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"APPLIED CRITICAL WHEY 5lbs - Ironmansupplements Benin","description":"CONSTRUIRE ET MAINTENIR MUSCLE : La poudre de prot\u00e9ine Applied Nutrition est un excellent moyen de d\u00e9velopper vos muscles lorsque vous faites de l'entra\u00eenement en force. Les prot\u00e9ines sont un \u00e9l\u00e9ment essentiel de votre alimentation pour aider \u00e0 maintenir votre masse musculaire, donc boire le shake comme recommand\u00e9 vous aidera \u00e0 maintenir votre d\u00e9veloppement musculaire.","canonical_url":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/","robots":"noindex, nofollow, max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en#listItem","position":1,"name":"Domicile","item":"http:\/\/benin.ironmansupplementsafrica.com\/en","nextItem":{"@type":"ListItem","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/boutique\/#listItem","name":"Boutique"}},{"@type":"ListItem","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/boutique\/#listItem","position":2,"name":"Boutique","item":"http:\/\/benin.ironmansupplementsafrica.com\/en\/boutique\/","nextItem":{"@type":"ListItem","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/categorie-produit\/protein-fr\/#listItem","name":"Protein"},"previousItem":{"@type":"ListItem","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en#listItem","name":"Domicile"}},{"@type":"ListItem","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/categorie-produit\/protein-fr\/#listItem","position":3,"name":"Protein","item":"http:\/\/benin.ironmansupplementsafrica.com\/en\/categorie-produit\/protein-fr\/","nextItem":{"@type":"ListItem","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/#listItem","name":"APPLIED CRITICAL WHEY 5lbs"},"previousItem":{"@type":"ListItem","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/boutique\/#listItem","name":"Boutique"}},{"@type":"ListItem","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/#listItem","position":4,"name":"APPLIED CRITICAL WHEY 5lbs","previousItem":{"@type":"ListItem","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/categorie-produit\/protein-fr\/#listItem","name":"Protein"}}]},{"@type":"ItemPage","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/#itempage","url":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/","name":"APPLIED CRITICAL WHEY 5lbs - Ironmansupplements Benin","description":"CONSTRUIRE ET MAINTENIR MUSCLE : La poudre de prot\u00e9ine Applied Nutrition est un excellent moyen de d\u00e9velopper vos muscles lorsque vous faites de l'entra\u00eenement en force. Les prot\u00e9ines sont un \u00e9l\u00e9ment essentiel de votre alimentation pour aider \u00e0 maintenir votre masse musculaire, donc boire le shake comme recommand\u00e9 vous aidera \u00e0 maintenir votre d\u00e9veloppement musculaire.","inLanguage":"fr-FR","isPartOf":{"@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/#website"},"breadcrumb":{"@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2024\/04\/CRITICAL-WHEY.png","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/#mainImage","width":1080,"height":1080},"primaryImageOfPage":{"@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/#mainImage"},"datePublished":"2024-04-05T10:05:15+00:00","dateModified":"2024-04-05T10:05:15+00:00"},{"@type":"Organization","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/#organization","name":"Ironmansupplements Benin","url":"http:\/\/benin.ironmansupplementsafrica.com\/en\/","logo":{"@type":"ImageObject","url":"http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2024\/02\/ironman_logo_112px_-removebg-preview.png","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/#organizationLogo","width":112,"height":112},"image":{"@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/#organizationLogo"}},{"@type":"WebSite","@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/#website","url":"http:\/\/benin.ironmansupplementsafrica.com\/en\/","name":"Ironmansupplements Benin","inLanguage":"fr-FR","publisher":{"@id":"http:\/\/benin.ironmansupplementsafrica.com\/en\/#organization"}}]},"og:locale":"fr_FR","og:site_name":"Ironmansupplements Benin -","og:type":"article","og:title":"APPLIED CRITICAL WHEY 5lbs - Ironmansupplements Benin","og:description":"CONSTRUIRE ET MAINTENIR MUSCLE : La poudre de prot\u00e9ine Applied Nutrition est un excellent moyen de d\u00e9velopper vos muscles lorsque vous faites de l'entra\u00eenement en force. Les prot\u00e9ines sont un \u00e9l\u00e9ment essentiel de votre alimentation pour aider \u00e0 maintenir votre masse musculaire, donc boire le shake comme recommand\u00e9 vous aidera \u00e0 maintenir votre d\u00e9veloppement musculaire.","og:url":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/","og:image":"http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2022\/11\/logo.png","article:published_time":"2024-04-05T10:05:15+00:00","article:modified_time":"2024-04-05T10:05:15+00:00","twitter:card":"summary_large_image","twitter:title":"APPLIED CRITICAL WHEY 5lbs - Ironmansupplements Benin","twitter:description":"CONSTRUIRE ET MAINTENIR MUSCLE : La poudre de prot\u00e9ine Applied Nutrition est un excellent moyen de d\u00e9velopper vos muscles lorsque vous faites de l'entra\u00eenement en force. Les prot\u00e9ines sont un \u00e9l\u00e9ment essentiel de votre alimentation pour aider \u00e0 maintenir votre masse musculaire, donc boire le shake comme recommand\u00e9 vous aidera \u00e0 maintenir votre d\u00e9veloppement musculaire.","twitter:image":"http:\/\/benin.ironmansupplementsafrica.com\/wp-content\/uploads\/sites\/9\/2022\/11\/logo.png"},"aioseo_meta_data":{"post_id":"7046","title":null,"description":null,"keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"ItemPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"limit_modified_date":false,"created":"2024-04-05 10:05:15","updated":"2026-08-17 11:53:30","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"ai":null,"breadcrumb_settings":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/benin.ironmansupplementsafrica.com\/en\" title=\"Domicile\">Domicile<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/benin.ironmansupplementsafrica.com\/en\/boutique\/\" title=\"Boutique\">Boutique<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"http:\/\/benin.ironmansupplementsafrica.com\/en\/categorie-produit\/protein-fr\/\" title=\"Protein\">Protein<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tAPPLIED CRITICAL WHEY 5lbs\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Domicile","link":"http:\/\/benin.ironmansupplementsafrica.com\/en"},{"label":"Boutique","link":"http:\/\/benin.ironmansupplementsafrica.com\/en\/boutique\/"},{"label":"Protein","link":"http:\/\/benin.ironmansupplementsafrica.com\/en\/categorie-produit\/protein-fr\/"},{"label":"APPLIED CRITICAL WHEY 5lbs","link":"http:\/\/benin.ironmansupplementsafrica.com\/en\/produit\/applied-critical-whey-5lbs\/"}],"_links":{"self":[{"href":"http:\/\/benin.ironmansupplementsafrica.com\/en\/wp-json\/wp\/v2\/product\/7046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/benin.ironmansupplementsafrica.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"http:\/\/benin.ironmansupplementsafrica.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"http:\/\/benin.ironmansupplementsafrica.com\/en\/wp-json\/wp\/v2\/comments?post=7046"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/benin.ironmansupplementsafrica.com\/en\/wp-json\/wp\/v2\/media\/7047"}],"wp:attachment":[{"href":"http:\/\/benin.ironmansupplementsafrica.com\/en\/wp-json\/wp\/v2\/media?parent=7046"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"http:\/\/benin.ironmansupplementsafrica.com\/en\/wp-json\/wp\/v2\/product_brand?post=7046"},{"taxonomy":"product_cat","embeddable":true,"href":"http:\/\/benin.ironmansupplementsafrica.com\/en\/wp-json\/wp\/v2\/product_cat?post=7046"},{"taxonomy":"product_tag","embeddable":true,"href":"http:\/\/benin.ironmansupplementsafrica.com\/en\/wp-json\/wp\/v2\/product_tag?post=7046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}